{"id":38396,"date":"2023-11-01T18:17:11","date_gmt":"2023-11-01T18:17:11","guid":{"rendered":"https:\/\/www.sando.com\/especialidades\/transport-infrastructure\/transport-and-mobility\/roads"},"modified":"2026-06-03T18:32:43","modified_gmt":"2026-06-03T18:32:43","slug":"roads","status":"publish","type":"page","link":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads","title":{"rendered":"roads"},"content":{"rendered":"\n\n    \n\n        <div class=\"total u-pT-xs u-pB-m u-pLR-container\">\n    <div class=\"container-max\">\n    <div class=\"row row-cols-1 g-3\">\n    \n\n    <div class=\"col\"><div class=\"total m-card --cardMax u-br-l u-pT-xxxl overflow-hidden u-white u-bg-verde-500\">\n    \t<div class=\"total __bxImg\">\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1900\" height=\"900\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia.jpg\" class=\"attachment-full size-full\" alt=\"carreteras autovia polonia\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia-120x57.jpg 120w\" sizes=\"auto, (max-width: 1900px) 100vw, 1900px\" \/> \n\t<\/div>\n    \t<div class=\"container-medium\">\n\t\t<div class=\"__bxCnt u-pLR-container\">\n                        <div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\n                                <p class=\"ht-body-m u-bold uppercase\"><a href=\"\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads\" title=\"We build and renovate highways, freeways and roads\" target=\"_blank\">Roads<\/a><\/p>\n                                <p><span class=\"ht-two u-light\">Building and innovating road networks that bring people together<\/span><\/p>\n            <\/div>\n                            <div class=\"__bxBtn total\">\n                    <div class=\"a-subtitArrow u-white\">\n                        <div class=\"__bxText ht-body-m uppercase u-bold\">we tell you more<\/div>\n                        <svg class=\"__icon\">\n                            <use xlink:href=\"#icon-border-arrow-down\" href=\"\/i.svg#icon-border-arrow-down\"><\/use>\n                        <\/svg>\n                    <\/div>\n                <\/div>\n            \t\t<\/div> \n\t<\/div>\n<\/div><\/div>\n\n    \n        <\/div>\n    <\/div>\n    <\/div>\n    \n\n\n<div class=\"total u-pLR-container\">\n    <div class=\"container-medium\">\n        <div class=\"total u-pT-s u-pB-s\">\n            <div class=\"total u-pB-xs \">\n                <ol class=\"m-breadcrumb\" itemscope itemtype=\"http:\/\/schema.org\/BreadcrumbList\"><li itemprop=\"itemListElement\" itemscope itemtype=\"http:\/\/schema.org\/ListItem\"><a href=\"https:\/\/www.sando.com\/en\" itemprop=\"item\"><span itemprop=\"name\">Home<\/span><\/a><meta itemprop=\"position\" content=\"1\" \/><\/li><\/ol>            <\/div>\n            <p class=\"ht-three u-light\">roads<\/p>\n        <\/div>\n    <\/div>\n<\/div>\n<div class=\"container-full u-mB-l u-verde-700 block-text-varios js-block-text-varios\"> \r\n\t<div class=\"container-max\">\r\n\t\t<div class=\"total u-bg-white u-br-l u-pTB-xl u-pLR-container overflow-hidden\">\r\n\t\t\t\t\t\t<div class=\"container-medium\">\r\n\t\t\t\t<div class=\"row row-cols-1 row-cols-lg-2 d-flex justify-content-between u-pB-s\" id=\"contenido\">\r\n\t\t\t\t\t<div class=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"a-tagTitle u-verde-700\">\r\n\t\t\t\t\t\t\t<svg class=\"u-verde-500\" width=\"9\" height=\"20\" viewBox=\"0 0 9 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n\t\t\t\t\t\t\t\t<path d=\"M0 0C6.414 0 8.78101 3.93299 8.78101 9.92699C8.78101 15.921 6.414 19.853 0 19.853V16.112C3.13 16.112 3.97101 13.668 3.97101 9.92699C3.97101 6.22699 3.131 3.78 0 3.78V0Z\" fill=\"currentColor\"\/>\r\n\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t\tconnecting people\t\t\t\t\t\t<\/div>\t\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col d-none justify-content-end d-lg-flex u-verde-700\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"container-medium u-verde-700\">\r\n\t\t\t\t<div class=\"total u-pB-l u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 800px;\">\r\n\t\t\t\t<p><span class=\"u-light ht-two\">We build and renovate highways, motorways and roads to adapt to the new needs that arise with the transformation of cities and towns.<br \/>\n<\/span><\/p>\n\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<div class=\"container-small\">\r\n\t\t\t\t<div class=\"total u-nmB-lastchild u-nmT-firstchild u-pB-xl\" style=\"max-width: 1000px;\">\r\n\t\t\t\t<p><span class=\"ht-body-l\" style=\"font-weight: 400;\">Sando offers its clients expertise in road construction and maintenance through Sando Infraestructuras y Proyectos and Sando Conservaci\u00f3n y Energ\u00eda, respectively, and integrates the latest technologies to achieve maximum connectivity between <a href=\"\/en\/specialisations\/transport-infrastructure\" title=\"Construction and maintenance of transportation infrastructure\" target=\"_blank\">Transportation Infrastructure<\/a>, vehicles, and travelers. As well as using sustainable materials of the highest quality and efficiency to improve road and passenger safety while reducing GHG emissions to the environment.<br \/>\n<\/span><\/p>\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\r\n\r\n\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n\r\n\n\n<div class=\"container-full u-mB-l u-verde-700 block-slider-content-posts\"> \r\n\t<div class=\"container-max\">\r\n\t\t<div class=\"total u-bg-verde-100 u-br-l u-pTB-xl u-pLR-container overflow-hidden\">\r\n\t\t\t\r\n\t\t\t\t\t\t<div class=\"container-medium\">\r\n\t\t\t\t<div class=\"row row-cols-1 row-cols-lg-2 d-flex justify-content-between u-pB-s\">\r\n\t\t\t\t\t<div class=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"a-tagTitle u-verde-700\">\r\n\t\t\t\t\t\t\t<svg class=\"u-verde-500\" width=\"9\" height=\"20\" viewBox=\"0 0 9 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n\t\t\t\t\t\t\t\t<path d=\"M0 0C6.414 0 8.78101 3.93299 8.78101 9.92699C8.78101 15.921 6.414 19.853 0 19.853V16.112C3.13 16.112 3.97101 13.668 3.97101 9.92699C3.97101 6.22699 3.131 3.78 0 3.78V0Z\" fill=\"currentColor\"\/>\r\n\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t\trelated projects\t\t\t\t\t\t<\/div>\t\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col d-none justify-content-end d-lg-flex u-verde-700\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/proyectos\/categoria\/carreteras\" title=\"See all\" class=\"a-btn-primary\" >\r\n\t\t\t\t\t\t\tSee all\t\t\t\r\n\t\t\t\t\t\t\t<svg class=\"__icon u-verde-500\">\r\n\t\t\t\t\t\t\t\t<use xlink:href=\"#icon-arrow-green-right\" href=\"\/i.svg#icon-arrow-green-right\"><\/use>\r\n\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\r\n\r\n\t\t\t<div class=\"container-medium u-verde-700\">\t\t\r\n\t\t\t\r\n\t\t\t<div class=\"m-slideDemo js-sldContentPost\">\r\n\t\t\t\t<div class=\"__loader u-bg-gray-500 u-br-m\">\r\n\t\t\t\t\t<div class=\"loader-01 u-verde-700\"><\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"__loop total\" \r\n\t\t\t\t\tdata-slidetoshow=\"2\"\r\n\t\t\t\t\tdata-slidetoshow-mob=\"1\"\r\n\t\t\t\t\tdata-slidetoshow-med=\"1\"\r\n\t\t\t\t\tdata-color-accent=\"u-verde-500\" \r\n\t\t\t\t\tstyle=\"opacity: 0; visibility:0;\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/05\/pabellon-carlos-iii-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n se encarga de los trabajos de rehabilitaci\u00f3n del edificio integral del pabell\u00f3n 12 del Instituto de Salud Carlos III.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/05\/pabellon-carlos-iii-1.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/05\/pabellon-carlos-iii-1-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/05\/pabellon-carlos-iii-1-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/05\/pabellon-carlos-iii-1-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/05\/pabellon-carlos-iii-1-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/05\/pabellon-carlos-iii-1-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\"><a href=\"\/en\/specialisations\/sustainable-building\" title=\"Sustainable building. Sustainable buildings that enrich the environment.\" target=\"_blank\">Sustainable building<\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Refurbishment of Pavilion 12 of the Carlos III Health Institute<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Madrid (Community of Madrid)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/refurbishment-of-pavilion-12-of-the-carlos-iii-health-institute\" title=\"Refurbishment of Pavilion 12 of the Carlos III Health Institute\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/sando-museo.arqueologico-alcala-henares.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando construye el nuevo edificio que act\u00faa como ampliaci\u00f3n del Museo Arqueol\u00f3gico Regional de la Comunidad de Madrid, en Alcal\u00e1 de Henares.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/sando-museo.arqueologico-alcala-henares.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/sando-museo.arqueologico-alcala-henares-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/sando-museo.arqueologico-alcala-henares-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/sando-museo.arqueologico-alcala-henares-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/sando-museo.arqueologico-alcala-henares-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/sando-museo.arqueologico-alcala-henares-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#construction-and-refurbishment-of-offices\" href=\"\/i.svg#construction-and-refurbishment-of-offices\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\"><a href=\"\/en\/specialisations\/sustainable-building\/construction-and-refurbishment-of-offices\" title=\"Construction and refurbishment of offices\" target=\"_blank\">Construction and refurbishment of offices<\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Alcal\u00e1 de Henares Archaeological Museum<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Madrid (Community of Madrid)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/alcala-de-henares-archaeological-museum\" title=\"Alcal\u00e1 de Henares Archaeological Museum\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/aljarafe-center.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n construye el Intercambiador de Transportes de Ciudad Expo en  el complejo Aljarafe Center en Sevilla.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/aljarafe-center.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/aljarafe-center-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/aljarafe-center-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/aljarafe-center-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/aljarafe-center-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/aljarafe-center-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#construction-and-refurbishment-of-offices\" href=\"\/i.svg#construction-and-refurbishment-of-offices\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Construction and refurbishment of offices<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Aljarafe Central Complex<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Seville (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/aljarafe-central-complex\" title=\"Aljarafe Central Complex\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/mantenimiento-viales-algeciras.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"El mantenimiento de viales en l bah\u00eda de Algeciras abarca distintas actuaciones en los puertos de la Autoridad Portuaria.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/mantenimiento-viales-algeciras.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/mantenimiento-viales-algeciras-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/mantenimiento-viales-algeciras-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/mantenimiento-viales-algeciras-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/mantenimiento-viales-algeciras-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/mantenimiento-viales-algeciras-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#smartcity\" href=\"\/i.svg#smartcity\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\"><a href=\"\/en\/specialisations\/urban-conservation-and-smart-cities\" title=\"Urban conservation\" target=\"_blank\">Urban conservation<\/a> and <a href=\"\/en\/specialisations\/urban-conservation-and-smart-cities\" title=\"Design of smart cities\" target=\"_blank\">smart cities<\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Maintenance of roads in the Bay of Algeciras<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Conservacion-y-Energia-negativo.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Algeciras (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/maintenance-of-roads-in-the-bay-of-algeciras\" title=\"Maintenance of roads in the Bay of Algeciras\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-victoria.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n realiza la reforma y ampliaci\u00f3n del Hospital de D\u00eda Onco-Hematol\u00f3gico del Hospital Virgen de la Victoria de M\u00e1laga.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-victoria.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-victoria-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-victoria-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-victoria-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-victoria-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-victoria-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Hospital Virgen de la Victoria<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">C\u00e1rtama (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/hospital-virgen-de-la-victoria\" title=\"Hospital Virgen de la Victoria\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-quiron-marbella.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Hospital Quir\u00f3n Marbella\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-quiron-marbella.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-quiron-marbella-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-quiron-marbella-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-quiron-marbella-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-quiron-marbella-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/hospital-quiron-marbella-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Hospital de Quir\u00f3nsalud en Marbella<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Marbella (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/hospital-de-quironsalud-en-marbella\" title=\"Hospital de Quir\u00f3nsalud en Marbella\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/viario-bormujos.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Conacon Sando se encarga del mantenimiento del viario de Bormujos en Sevilla, con acciones para la mejora de la accesibilidad.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/viario-bormujos.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/viario-bormujos-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/viario-bormujos-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/viario-bormujos-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/viario-bormujos-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/viario-bormujos-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#smartcity\" href=\"\/i.svg#smartcity\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Urban conservation and smart cities<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Bormujos Road Maintenance<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Conservacion-y-Energia-negativo.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Seville (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/bormujos-road-maintenance\" title=\"Bormujos Road Maintenance\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/castellana-44.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Rehabilitaci\u00f3n del edificio del Consorcio de Compensaci\u00f3n de Seguros, situado en el Paseo de la Castellana 44 Madrid.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/castellana-44.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/castellana-44-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/castellana-44-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/castellana-44-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/castellana-44-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/castellana-44-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Consorcio Seguros Building Castellana 44<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Madrid (Community of Madrid)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/consorcio-seguros-building-castellana-44\" title=\"Consorcio Seguros Building Castellana 44\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/logisticas-mayoral.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n ejecuta las nuevas instalaciones log\u00edsticas de Mayoral Moda Infantil en el pol\u00edgono industrial Intelhorce, en M\u00e1laga.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/logisticas-mayoral.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/logisticas-mayoral-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/logisticas-mayoral-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/logisticas-mayoral-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/logisticas-mayoral-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/logisticas-mayoral-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Mayoral&#8217;s logistics facilities in Malaga<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">C\u00e1rtama (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/mayorals-logistics-facilities-in-malaga\" title=\"Mayoral&#8217;s logistics facilities in Malaga\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/complejo-velazquez.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Edificio Vel\u00e1zquez\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/complejo-velazquez.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/complejo-velazquez-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/complejo-velazquez-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/complejo-velazquez-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/complejo-velazquez-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/complejo-velazquez-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#construction-and-refurbishment-of-offices\" href=\"\/i.svg#construction-and-refurbishment-of-offices\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Construction and refurbishment of offices<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Vel\u00e1zquez Building<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Madrid (Community of Madrid)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/velazquez-building-2\" title=\"Vel\u00e1zquez Building\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-del-puerto-santa-maria.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando ejecuta la nueva comisar\u00eda del Puerto de Santa Mar\u00eda bajo los criterios del sello de certificaci\u00f3n sostenible \u201c3 hojas\u201d del GBCe.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-del-puerto-santa-maria.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-del-puerto-santa-maria-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-del-puerto-santa-maria-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-del-puerto-santa-maria-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-del-puerto-santa-maria-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-del-puerto-santa-maria-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">New police station in Puerto de Santa Mar\u00eda in C\u00e1diz<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Puente Genil (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/new-police-station-in-puerto-de-santa-maria-in-cadiz\" title=\"New police station in Puerto de Santa Mar\u00eda in C\u00e1diz\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/fotovoltaica-flotante-andevalo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Energ\u00eda solar fotovoltaica para And\u00e9valo Pedro Arco\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/fotovoltaica-flotante-andevalo.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/fotovoltaica-flotante-andevalo-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/fotovoltaica-flotante-andevalo-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/fotovoltaica-flotante-andevalo-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/fotovoltaica-flotante-andevalo-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/fotovoltaica-flotante-andevalo-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#energia\" href=\"\/i.svg#energia\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\"><a href=\"\/en\/specialisations\/energy-and-decarbonisation\" title=\"Energy and decarbonization. Alternative energy solutions and energy efficiency systems.\" target=\"_blank\">Energy and decarbonisation<\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Photovoltaic solar energy for the And\u00e9valo Pedro Arco irrigation community in Huelva<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Conservacion-y-Energia-negativo.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Huelva (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/photovoltaic-solar-energy-for-the-andevalo-pedro-arco-irrigation-community-in-huelva\" title=\"Photovoltaic solar energy for the And\u00e9valo Pedro Arco irrigation community in Huelva\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/calle-100-por-cien-sostenible.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Conacon Sando ejecuta la calle 100% sostenible de Tenerife, en las islas Canarias, ubicada en avenida La Constituci\u00f3n.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/calle-100-por-cien-sostenible.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/calle-100-por-cien-sostenible-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/calle-100-por-cien-sostenible-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/calle-100-por-cien-sostenible-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/calle-100-por-cien-sostenible-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/calle-100-por-cien-sostenible-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#smartcity\" href=\"\/i.svg#smartcity\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Urban conservation and smart cities<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">100% sustainable street in Tenerife<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Conservacion-y-Energia-negativo.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Santa Cruz de Tenerife (Canary Islands)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/100-sustainable-street-in-tenerife\" title=\"100% sustainable street in Tenerife\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-soria-sando.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n ejecuta La nueva comisar\u00eda provincial en Soria bajo el sello de certificaci\u00f3n sostenible \u201c3 hojas\u201d del GBCe.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-soria-sando.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-soria-sando-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-soria-sando-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-soria-sando-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-soria-sando-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-soria-sando-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">New provincial police station in Soria<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Soria (Castilla y Le\u00f3n)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/new-provincial-police-station-in-soria\" title=\"New provincial police station in Soria\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-los-madrazo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"La Sede de la Unidad de Seguridad Privada de la Polic\u00eda Nacional la ejecuta Sando Construcci\u00f3n bajo el sello \u201c3 hojas\u201d del GBCe.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-los-madrazo.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-los-madrazo-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-los-madrazo-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-los-madrazo-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-los-madrazo-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-los-madrazo-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">National Police Private Security Unit Headquarters<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Madrid (Community of Madrid)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/national-police-private-security-unit-headquarters\" title=\"National Police Private Security Unit Headquarters\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-cordoba.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n ejecuta la nueva comisar\u00eda de C\u00f3rdoba bajo los criterios del sello \u201c3 hojas\u201d del GBCe, Green Building Council Espa\u00f1a.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-cordoba.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-cordoba-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-cordoba-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-cordoba-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-cordoba-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-cordoba-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Cordoba East District Police Station<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Puente Genil (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/cordoba-east-district-police-station\" title=\"Cordoba East District Police Station\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-centro-leganitos.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Nueva Comisar\u00eda Distrito Centro de Madrid en Leganitos, ejecutada por Sando Construcci\u00f3n bajo la Certificaci\u00f3n VERDE.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-centro-leganitos.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-centro-leganitos-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-centro-leganitos-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-centro-leganitos-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-centro-leganitos-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/comisaria-centro-leganitos-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Madrid Central District Police Station<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Madrid (Community of Madrid)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/madrid-central-district-police-station\" title=\"Madrid Central District Police Station\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/nueva-sede-de-RTVE-en-castilla-y-leon.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n ejecuta la Nueva sede de RTVE en Castilla y Le\u00f3n\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/nueva-sede-de-RTVE-en-castilla-y-leon.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/nueva-sede-de-RTVE-en-castilla-y-leon-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/nueva-sede-de-RTVE-en-castilla-y-leon-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/nueva-sede-de-RTVE-en-castilla-y-leon-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/nueva-sede-de-RTVE-en-castilla-y-leon-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/04\/nueva-sede-de-RTVE-en-castilla-y-leon-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#sostenible\" href=\"\/i.svg#sostenible\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Sustainable building<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">New RTVE headquarters in Castilla y Le\u00f3n<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Valladolid (Castilla y Le\u00f3n)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/new-rtve-headquarters-in-castilla-y-leon\" title=\"New RTVE headquarters in Castilla y Le\u00f3n\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-el-canaveral.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Urbanizaci\u00f3n El Ca\u00f1averal\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-el-canaveral.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-el-canaveral-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-el-canaveral-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-el-canaveral-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-el-canaveral-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-el-canaveral-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#smartcity\" href=\"\/i.svg#smartcity\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Urban conservation and smart cities<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Urbanisation El Ca\u00f1averal<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Madrid (Community of Madrid)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/urbanisation-el-canaveral\" title=\"Urbanisation El Ca\u00f1averal\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-martiricos.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Urbanizaci\u00f3n Martiricos\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-martiricos.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-martiricos-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-martiricos-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-martiricos-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-martiricos-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-martiricos-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#smartcity\" href=\"\/i.svg#smartcity\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Urban conservation and smart cities<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Urbanisation Martiricos<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">C\u00e1rtama (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/urbanisation-martiricos\" title=\"Urbanisation Martiricos\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pato.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sector El Pato\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pato.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pato-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pato-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pato-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pato-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pato-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#smartcity\" href=\"\/i.svg#smartcity\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Urban conservation and smart cities<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">El Pato Sector<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">C\u00e1rtama (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/el-pato-sector\" title=\"El Pato Sector\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pozuelo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Urbanizaci\u00f3n El Pozuelo\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pozuelo.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pozuelo-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pozuelo-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pozuelo-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pozuelo-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/urbanizacion-el-pozuelo-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#smartcity\" href=\"\/i.svg#smartcity\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Urban conservation and smart cities<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Urbanisation El Pozuelo<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Torremolinos (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/urbanisation-el-pozuelo\" title=\"Urbanisation El Pozuelo\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-francisco-montenegro.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Acondicionamiento de la Avenida Francisco Montenegro\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-francisco-montenegro.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-francisco-montenegro-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-francisco-montenegro-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-francisco-montenegro-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-francisco-montenegro-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizacion-francisco-montenegro-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#smartcity\" href=\"\/i.svg#smartcity\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Urban conservation and smart cities<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Upgrading of Avenida Francisco Montenegro<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Huelva (Andalusia)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/upgrading-of-avenida-francisco-montenegro\" title=\"Upgrading of Avenida Francisco Montenegro\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-card --cardMinProyecto u-br-l overflow-hidden u-white u-bg-verde-500\">\n\t\t<div class=\"total __bxImg\">\n\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-la-platina-salamanca.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Urbanizaci\u00f3n La Platina de Salamanca\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-la-platina-salamanca.jpg 1900w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-la-platina-salamanca-250x118.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-la-platina-salamanca-700x332.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-la-platina-salamanca-768x364.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-la-platina-salamanca-1536x728.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2023\/10\/urbanizaciones-la-platina-salamanca-120x57.jpg 120w\" sizes=\"(max-width: 1900px) 100vw, 1900px\" \/>\t<\/div>\n\t\t\n\t<div class=\"__bxCnt u-pLR-container \">\n\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild\" style=\"max-width: 680px;\">\t\t\n\t\t\t\t\t\t\t<div class=\"__bx total u-pB-xs\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#smartcity\" href=\"\/i.svg#smartcity\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Urban conservation and smart cities<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"ht-two u-light\">Urbanizaci\u00f3n La Platina de Salamanca<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t<div class=\"__bx\"><img loading=\"lazy\" decoding=\"async\" width=\"75\" height=\"49\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Sando-Infraestructuras-y-Proyectos-Negativo-.svg\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\t\t\t\t<div class=\"__bx\">\n\t\t\t\t\t<div class=\"a-iconText u-white\">\n\t\t\t\t\t\t<svg class=\"__icon\">\n\t\t\t\t\t\t\t<use xlink:href=\"#icon-location\" href=\"\/i.svg#icon-location\"><\/use>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<div class=\"__bxText ht-body-m uppercase u-bold\">Salamanca (Castilla y Le\u00f3n)<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"__bxLink total u-pT-s\">\n\t\t\t\t<a href=\"https:\/\/www.sando.com\/en\/proyectos\/urbanizacion-la-platina-de-salamanca\" title=\"Urbanizaci\u00f3n La Platina de Salamanca\" class=\"a-btn-primary u-white --without-br\">\n\t\t\t\t\tAbout the project\t\t\t\t\t\n\t\t\t\t\t<svg class=\"__icon\"><use xlink:href=\"#icon-border-arrow-right\" href=\"\/i.svg#icon-border-arrow-right\"><\/use><\/svg>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"__footer total u-pT-s\">\r\n\t\t\t\t\t<div class=\"__bx d-flex gap-4\">\r\n\t\t\t\t\t\t<div class=\"__arrow-prev a-arrowSliderCircle\" role=\"button\" aria-label=\"Anterior\">\r\n\t\t\t\t\t\t\t<svg class=\"a-icon\"><use xlink:href=\"#icon-arrow-green-left-max\" href=\"\/i.svg#icon-arrow-green-left-max\"><\/use><\/svg>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"__arrow-next a-arrowSliderCircle\" role=\"button\" aria-label=\"Siguiente\">\r\n\t\t\t\t\t\t\t<svg class=\"a-icon\"><use xlink:href=\"#icon-arrow-green-right-max\" href=\"\/i.svg#icon-arrow-green-right-max\"><\/use><\/svg>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"__bx d-flex\">\r\n\t\t\t\t\t\t<div class=\"__counter\">\r\n\t\t\t\t\t\t\t<span class=\"ht-body-m u-bold __pageInfo\"><\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"total d-block d-lg-none u-pT-xl u-verde-700\">\r\n\t\t\t\t<a href=\"\/proyectos\/categoria\/carreteras\" title=\"See all\" class=\"a-btn-primary\" >\r\n\t\t\t\t\tSee all\t\t\t\r\n\t\t\t\t\t<svg class=\"__icon u-verde-500\">\r\n\t\t\t\t\t\t<use xlink:href=\"#icon-arrow-green-right\" href=\"\/i.svg#icon-arrow-green-right\"><\/use>\r\n\t\t\t\t\t<\/svg>\r\n\t\t\t\t<\/a>\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"container-full u-mB-l u-verde-700 block-slider-content-posts\"> \r\n\t<div class=\"container-max\">\r\n\t\t<div class=\"total u-bg-white u-br-l u-pTB-xl u-pLR-container overflow-hidden\">\r\n\t\t\t\r\n\t\t\t\t\t\t<div class=\"container-medium\">\r\n\t\t\t\t<div class=\"row row-cols-1 row-cols-lg-2 d-flex justify-content-between u-pB-s\">\r\n\t\t\t\t\t<div class=\"col\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"a-tagTitle u-verde-700\">\r\n\t\t\t\t\t\t\t<svg class=\"u-verde-500\" width=\"9\" height=\"20\" viewBox=\"0 0 9 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n\t\t\t\t\t\t\t\t<path d=\"M0 0C6.414 0 8.78101 3.93299 8.78101 9.92699C8.78101 15.921 6.414 19.853 0 19.853V16.112C3.13 16.112 3.97101 13.668 3.97101 9.92699C3.97101 6.22699 3.131 3.78 0 3.78V0Z\" fill=\"currentColor\"\/>\r\n\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t\t<h2>News Infrastructures<\/h2>\t\t\t\t\t\t<\/div>\t\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"col d-none justify-content-end d-lg-flex u-verde-700\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/en\/news\/category\/business\/infrastructure\" title=\"News\" class=\"a-btn-primary\" >\r\n\t\t\t\t\t\t\tSee all\t\t\t\r\n\t\t\t\t\t\t\t<svg class=\"__icon u-verde-500\">\r\n\t\t\t\t\t\t\t\t<use xlink:href=\"#icon-arrow-green-right\" href=\"\/i.svg#icon-arrow-green-right\"><\/use>\r\n\t\t\t\t\t\t\t<\/svg>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\r\n\r\n\r\n\t\t\t<div class=\"container-medium u-verde-700\">\t\t\r\n\t\t\t\r\n\t\t\t<div class=\"m-slideDemo js-sldContentPost\">\r\n\t\t\t\t<div class=\"__loader u-bg-gray-500 u-br-m\">\r\n\t\t\t\t\t<div class=\"loader-01 u-verde-700\"><\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"__loop total\" \r\n\t\t\t\t\tdata-slidetoshow=\"3\"\r\n\t\t\t\t\tdata-slidetoshow-mob=\"1\"\r\n\t\t\t\t\tdata-slidetoshow-med=\"2\"\r\n\t\t\t\t\tdata-color-accent=\"u-verde-500\" \r\n\t\t\t\t\tstyle=\"opacity: 0; visibility:0;\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"El grupo de empresas Sando ha llevado a cabo un proceso de renovaci\u00f3n de la identidad corporativa de sus principales marcas con el objetivo de actualizar sus denominaciones y reforzar su posicionamiento en los \u00e1mbitos de las infraestructuras y los servicios.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia.jpg 1200w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia-250x157.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia-700x440.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia-768x483.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia-120x76.jpg 120w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando redefine su arquitectura de marca y refuerza su posicionamiento en infraestructuras y servicios<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-infraestructuras-y-proyectos-sando-conservacion-y-energia-arquitectura-de-marca\" title=\"Sando redefine su arquitectura de marca y refuerza su posicionamiento en infraestructuras y servicios\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Captura-BIM-Viera-Clavijo-e1778674810840.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Infraestructuras y Proyectos y Sando Conservaci\u00f3n y Energ\u00eda han superado las auditor\u00edas de seguimiento realizadas por la entidad AENOR conforme a la norma internacional ISO 19650 (partes 1 y 2). Esta certificaci\u00f3n acredita la correcta gesti\u00f3n de la informaci\u00f3n en proyectos desarrollados con metodolog\u00eda BIM en la compa\u00f1\u00eda.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando passes the AENOR audit for BIM certification in accordance with ISO 19650<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-passes-the-aenor-audit-for-bim-certification-in-accordance-with-iso-19650\" title=\"Sando passes the AENOR audit for BIM certification in accordance with ISO 19650\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Conservaci\u00f3n y Energ\u00eda lidera el proyecto SOTER, una innovadora iniciativa de I+D+i orientada al desarrollo de un sistema avanzado para la inspecci\u00f3n automatizada del estado de los pavimentos, basado en el uso de im\u00e1genes de sat\u00e9lite de muy alta resoluci\u00f3n e inteligencia artificial que permite desarrollar un mantenimiento preventivo en grandes superficies.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER.jpg 960w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER-250x310.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER-700x869.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER-768x954.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER-120x149.jpg 120w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando applies satellite imagery and AI in SOTER innovation project to improve road maintenance<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-aplica-imagenes-satelitales-e-ia-en-el-proyecto-de-innovacion-soter-para-mejorar-la-conservacion-de-carreteras\" title=\"Sando applies satellite imagery and AI in SOTER innovation project to improve road maintenance\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/06\/woman-foward-ranking-empresas-igualdad-sando-construccion-esm.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n entra en el Ranking de Empresas por la Igualdad\u00a0en el n\u00famero 29, la \u00fanica constructora del pa\u00eds\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/06\/woman-foward-ranking-empresas-igualdad-sando-construccion-esm.jpg 1200w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/06\/woman-foward-ranking-empresas-igualdad-sando-construccion-esm-250x167.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/06\/woman-foward-ranking-empresas-igualdad-sando-construccion-esm-700x467.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/06\/woman-foward-ranking-empresas-igualdad-sando-construccion-esm-768x512.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/06\/woman-foward-ranking-empresas-igualdad-sando-construccion-esm-120x80.jpg 120w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\"><a href=\"\/en\/sando-construccion\" title=\"Sando Construcci\u00f3n. Building resilient and innovative infrastructures\" target=\"_blank\">Sando Construcci\u00f3n<\/a> enters the Corporate Equality Index at number 29, the only construction company in the country<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-construccion-enters-the-corporate-equality-index-at-number-29-the-only-construction-company-in-the-country\" title=\"Sando Construcci\u00f3n enters the Corporate Equality Index at number 29, the only construction company in the country\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Inauguracion-corredor-pizarra.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Se ha inaugurado el nuevo tramo del Corredor Verde construido por Sando en Pizarra. Un proyecto para la recuperaci\u00f3n del r\u00edo Guadalhorce.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Inauguracion-corredor-pizarra.jpg 1200w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Inauguracion-corredor-pizarra-250x167.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Inauguracion-corredor-pizarra-700x467.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Inauguracion-corredor-pizarra-768x512.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Inauguracion-corredor-pizarra-120x80.jpg 120w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Inauguration of the Green Corridor between Pizarra and La Vega Hip\u00f3lito<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/inauguration-of-the-green-corridor-between-pizarra-and-la-vega-hipolito\" title=\"Inauguration of the Green Corridor between Pizarra and La Vega Hip\u00f3lito\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Basaurbe-de-Llodio.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando realiza la construcci\u00f3n de la  EDAR de Basaurbe en Llodio para la Confederaci\u00f3n Hidrogr\u00e1fica del Cant\u00e1brico (CHC).\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Basaurbe-de-Llodio.jpg 1200w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Basaurbe-de-Llodio-250x167.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Basaurbe-de-Llodio-700x467.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Basaurbe-de-Llodio-768x512.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/Basaurbe-de-Llodio-120x80.jpg 120w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando builds the Basaurbe WWTP in the Basque Country to serve the population of Llodio<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-builds-the-basaurbe-wwtp-in-the-basque-country-to-serve-the-population-of-llodio\" title=\"Sando builds the Basaurbe WWTP in the Basque Country to serve the population of Llodio\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/tranvibussevilla.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"La Junta de Gobierno del Ayuntamiento de Sevilla ha encargado a Sando las primeras obras del tranvib\u00fas por 20,7 millones de euros.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/tranvibussevilla.jpg 1200w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/tranvibussevilla-250x167.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/tranvibussevilla-700x467.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/tranvibussevilla-768x512.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/02\/tranvibussevilla-120x80.jpg 120w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando to build the new Seville Tramway<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-to-build-the-new-seville-tramway\" title=\"Sando to build the new Seville Tramway\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/comisariacordoba.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/comisariacordoba.jpg 1200w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/comisariacordoba-250x167.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/comisariacordoba-700x467.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/comisariacordoba-768x512.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2024\/01\/comisariacordoba-120x80.jpg 120w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando will build the new police station in the Eastern District of Cordoba<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-will-build-the-new-police-station-in-the-eastern-district-of-cordoba\" title=\"Sando will build the new police station in the Eastern District of Cordoba\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"__footer total u-pT-s\">\r\n\t\t\t\t\t<div class=\"__bx d-flex gap-4\">\r\n\t\t\t\t\t\t<div class=\"__arrow-prev a-arrowSliderCircle\" role=\"button\" aria-label=\"Anterior\">\r\n\t\t\t\t\t\t\t<svg class=\"a-icon\"><use xlink:href=\"#icon-arrow-green-left-max\" href=\"\/i.svg#icon-arrow-green-left-max\"><\/use><\/svg>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"__arrow-next a-arrowSliderCircle\" role=\"button\" aria-label=\"Siguiente\">\r\n\t\t\t\t\t\t\t<svg class=\"a-icon\"><use xlink:href=\"#icon-arrow-green-right-max\" href=\"\/i.svg#icon-arrow-green-right-max\"><\/use><\/svg>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"__bx d-flex\">\r\n\t\t\t\t\t\t<div class=\"__counter\">\r\n\t\t\t\t\t\t\t<span class=\"ht-body-m u-bold __pageInfo\"><\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"total d-block d-lg-none u-pT-xl u-verde-700\">\r\n\t\t\t\t<a href=\"\/en\/news\/category\/business\/infrastructure\" title=\"News\" class=\"a-btn-primary\" >\r\n\t\t\t\t\tSee all\t\t\t\r\n\t\t\t\t\t<svg class=\"__icon u-verde-500\">\r\n\t\t\t\t\t\t<use xlink:href=\"#icon-arrow-green-right\" href=\"\/i.svg#icon-arrow-green-right\"><\/use>\r\n\t\t\t\t\t<\/svg>\r\n\t\t\t\t<\/a>\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t<\/div>\r\n<\/div><div class=\"container-full u-mB-l u-verde-700 block-slider-content-posts\"> \r\n\t<div class=\"container-max\">\r\n\t\t<div class=\"total u-bg-white u-br-l u-pTB-xl u-pLR-container overflow-hidden\">\r\n\t\t\t\r\n\t\t\t\t\t\t\r\n\r\n\r\n\t\t\t<div class=\"container-medium u-verde-700\">\t\t\r\n\t\t\t\r\n\t\t\t<div class=\"m-slideDemo js-sldContentPost\">\r\n\t\t\t\t<div class=\"__loader u-bg-gray-500 u-br-m\">\r\n\t\t\t\t\t<div class=\"loader-01 u-verde-700\"><\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"__loop total\" \r\n\t\t\t\t\tdata-slidetoshow=\"1\"\r\n\t\t\t\t\tdata-slidetoshow-mob=\"1\"\r\n\t\t\t\t\tdata-slidetoshow-med=\"1\"\r\n\t\t\t\t\tdata-color-accent=\"u-verde-500\" \r\n\t\t\t\t\tstyle=\"opacity: 0; visibility:0;\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"El grupo de empresas Sando ha llevado a cabo un proceso de renovaci\u00f3n de la identidad corporativa de sus principales marcas con el objetivo de actualizar sus denominaciones y reforzar su posicionamiento en los \u00e1mbitos de las infraestructuras y los servicios.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia.jpg 1200w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia-250x157.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia-700x440.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia-768x483.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/06\/Montaje-Marcas-Sando-copia-120x76.jpg 120w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando redefine su arquitectura de marca y refuerza su posicionamiento en infraestructuras y servicios<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-infraestructuras-y-proyectos-sando-conservacion-y-energia-arquitectura-de-marca\" title=\"Sando redefine su arquitectura de marca y refuerza su posicionamiento en infraestructuras y servicios\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/pacto-global.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando contin\u00faa consolidando su compromiso con la sostenibilidad mediante la adhesi\u00f3n a tres iniciativas estrat\u00e9gicas impulsadas por el Pacto Mundial de las Naciones Unidas. Estos proyectos, de alcance internacional, se integran en el Plan Director de Sostenibilidad 2025-2028 y refuerzan la actuaci\u00f3n de la compa\u00f1\u00eda en \u00e1mbitos clave como la gesti\u00f3n responsable de la cadena de suministro, el respeto a los derechos humanos y la descarbonizaci\u00f3n.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/pacto-global.png 1224w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/pacto-global-250x147.png 250w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/pacto-global-700x412.png 700w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/pacto-global-768x452.png 768w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/pacto-global-120x71.png 120w\" sizes=\"(max-width: 1224px) 100vw, 1224px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando reinforces its <a href=\"\/en\/sustainability\" title=\"Sustainable and efficient environmental solutions\" target=\"_blank\">Sustainability<\/a> strategy with three international initiatives of the UN Global Compact<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-reinforces-its-sustainability-strategy-with-three-international-initiatives-of-the-un-global-compact\" title=\"Sando reinforces its sustainability strategy with three international initiatives of the UN Global Compact\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Imagen-Equipo-Fundacion-Sando-e1779787954620.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"Fundaci\u00f3n Sando ha vuelto a estar presente en el Torneo Solidario de F\u00fatbol\u20117 HRUM-Ibima Plataforma Bionand, una cita ya consolidada que une deporte, ciencia y compromiso social. La entidad ha participado con un equipo formado por profesionales del grupo, manteniendo as\u00ed su presencia en las cuatro ediciones celebradas hasta la fecha para conseguir fondos para la investigaci\u00f3n biom\u00e9dica.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Fundaci\u00f3n Sando plays one more year the IBIMA 7-a-side Football Tournament for biomedical research<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/fundacion-sando-plays-one-more-year-the-ibima-7-a-side-football-tournament-for-biomedical-research\" title=\"Fundaci\u00f3n Sando plays one more year the IBIMA 7-a-side Football Tournament for biomedical research\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Limpieza-Puerto-Granadilla-Abona-HV-Hondius-e1779449506992.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Conservaci\u00f3n y Energ\u00eda interviene en la desinfecci\u00f3n del Puerto de Granadilla tras la evacuaci\u00f3n del buque MV Hondius por hantavirus\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando Conservaci\u00f3n y Energ\u00eda intervenes in the disinfection of the Port of Granadilla after the evacuation of the MV Hondius vessel<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-conservacion-y-energia-intervenes-in-the-disinfection-of-the-port-of-granadilla-after-the-evacuation-of-the-mv-hondius-vessel\" title=\"Sando Conservaci\u00f3n y Energ\u00eda intervenes in the disinfection of the Port of Granadilla after the evacuation of the MV Hondius vessel\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Captura-BIM-Viera-Clavijo-e1778674810840.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Infraestructuras y Proyectos y Sando Conservaci\u00f3n y Energ\u00eda han superado las auditor\u00edas de seguimiento realizadas por la entidad AENOR conforme a la norma internacional ISO 19650 (partes 1 y 2). Esta certificaci\u00f3n acredita la correcta gesti\u00f3n de la informaci\u00f3n en proyectos desarrollados con metodolog\u00eda BIM en la compa\u00f1\u00eda.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando passes the AENOR audit for BIM certification in accordance with ISO 19650<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-passes-the-aenor-audit-for-bim-certification-in-accordance-with-iso-19650\" title=\"Sando passes the AENOR audit for BIM certification in accordance with ISO 19650\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Firma-FMAEC-4-scaled-e1778233949695.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"La Fundaci\u00f3n Sando y Fundaci\u00f3n Malague\u00f1a de Asistencia a Enfermos de C\u00e1ncer (FMAEC) han firmado un acuerdo de colaboraci\u00f3n para trabajar conjuntamente en iniciativas destinadas a apoyar a las personas afectadas por el c\u00e1ncer y a fortalecer los recursos asistenciales que esta entidad ofrece en M\u00e1laga.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\"><a href=\"https:\/\/www.sando.com\/en\/about-us\/fundacion-sando\" title=\"We are building a more humane, caring and respectful future\" target=\"_blank\">Sando foundation<\/a> and FMAEC sign a commitment to collaborate with cancer patients<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-foundation-and-fmaec-sign-a-commitment-to-collaborate-with-cancer-patients\" title=\"Sando Foundation and FMAEC sign a commitment to collaborate with cancer patients\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Conservaci\u00f3n y Energ\u00eda lidera el proyecto SOTER, una innovadora iniciativa de I+D+i orientada al desarrollo de un sistema avanzado para la inspecci\u00f3n automatizada del estado de los pavimentos, basado en el uso de im\u00e1genes de sat\u00e9lite de muy alta resoluci\u00f3n e inteligencia artificial que permite desarrollar un mantenimiento preventivo en grandes superficies.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER.jpg 960w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER-250x310.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER-700x869.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER-768x954.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/05\/Deteccion-Objetos-Senalizacion-SOTER-120x149.jpg 120w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando applies satellite imagery and AI in SOTER innovation project to improve road maintenance<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-aplica-imagenes-satelitales-e-ia-en-el-proyecto-de-innovacion-soter-para-mejorar-la-conservacion-de-carreteras\" title=\"Sando applies satellite imagery and AI in SOTER innovation project to improve road maintenance\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/04\/Foto-Agradecimiento-Fundacion-Sando-e1777550590844.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"El Club de Voleibol Cuesta Piedra de Santa Cruz de Tenerife ha sellado este fin de semana su ascenso a la Liga Iberdrola, la m\u00e1xima categor\u00eda del voleibol femenino nacional.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">The Cuesta Piedra Volleyball Club of Santa Cruz de Tenerife is promoted to the highest national category<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/the-cuesta-piedra-volleyball-club-of-santa-cruz-de-tenerife-is-promoted-to-the-highest-national-category\" title=\"The Cuesta Piedra Volleyball Club of Santa Cruz de Tenerife is promoted to the highest national category\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/04\/Dia-Internacional-Seguridad-Salud-1200x800-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"El Servicio de Prevenci\u00f3n Mancomunado de Sando ha puesto en marcha un nuevo proyecto de transformaci\u00f3n digital orientado a reforzar su modelo de gesti\u00f3n preventiva integral. La compa\u00f1\u00eda incorpora una nueva plataforma de planificaci\u00f3n de recursos empresariales (ERP) que permitir\u00e1 organizar, automatizar y controlar los procesos asociados a la prevenci\u00f3n de riesgos laborales en todas sus \u00e1reas de producci\u00f3n.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/04\/Dia-Internacional-Seguridad-Salud-1200x800-1.jpg 1200w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/04\/Dia-Internacional-Seguridad-Salud-1200x800-1-250x167.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/04\/Dia-Internacional-Seguridad-Salud-1200x800-1-700x467.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/04\/Dia-Internacional-Seguridad-Salud-1200x800-1-768x512.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/04\/Dia-Internacional-Seguridad-Salud-1200x800-1-120x80.jpg 120w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando advances in the digitalization of prevention with a new comprehensive ORP platform<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-advances-in-the-digitalization-of-prevention-with-a-new-comprehensive-orp-platform\" title=\"Sando advances in the digitalization of prevention with a new comprehensive ORP platform\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/04\/Programa-Proveedores-Sostenibles-e1776166557684.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando ha confirmado un a\u00f1o m\u00e1s su adhesi\u00f3n al Programa de Capacitaci\u00f3n: Proveedores Sostenibles, una iniciativa impulsada por el Pacto Mundial de la ONU Espa\u00f1a, ICEX y la Fundaci\u00f3n ICO, que se ha consolidado como un proyecto formativo de referencia para el fortalecimiento de la sostenibilidad en las cadenas de suministro.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando renews its commitment to the Sustainable Suppliers Programme of the UN Global Compact<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-renews-its-commitment-to-the-sustainable-suppliers-programme-of-the-un-global-compact\" title=\"Sando renews its commitment to the Sustainable Suppliers Programme of the UN Global Compact\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/04\/ESIEM1-scaled-e1775043363804.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando ha formado parte este mes en dos iniciativas clave de impulso al talento joven y de promoci\u00f3n de las vocaciones vinculadas a la ingenier\u00eda: el Encuentro sobre Ingenier\u00eda y Empleo ESIEM 2026 y las VIII Olimpiadas Nacionales de Ingenier\u00eda de Caminos, Canales y Puertos.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando participates in ESIEM 2026 and in the VIII Road Olympics<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-participates-in-esiem-2026-and-in-the-viii-road-olympics\" title=\"Sando participates in ESIEM 2026 and in the VIII Road Olympics\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Althenia-Sando-Plan-Reforestacion-gibralfaro-scaled-e1774441840381.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Althenia Sando llevar\u00e1 a cabo un nuevo plan de reforestaci\u00f3n puesto en marcha por el Ayuntamiento de M\u00e1laga, a trav\u00e9s del \u00c1rea de Sostenibilidad Medioambiental.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\"><a href=\"\/en\/althenia-sando\" title=\"Althenia Sando. Integral environmental services\" target=\"_blank\">Althenia Sando<\/a> will plant 9,000 trees through Malaga&#8217;s reforestation plan<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/althenia-sando-will-plant-9000-trees-through-malagas-reforestation-plan\" title=\"Althenia Sando will plant 9,000 trees through Malaga&#8217;s reforestation plan\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Entrada-copia-e1774619240198.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n, a trav\u00e9s de su l\u00ednea especializada en infraestructuras sanitarias, ha finalizado el proyecto de ampliaci\u00f3n del Hospital Comarcal de la Axarqu\u00eda. Una intervenci\u00f3n estrat\u00e9gica que ha permitido incrementar los espacios funcionales del centro y habilitar nuevas dependencias destinadas a la asistencia sanitaria.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando Construcci\u00f3n completes the expansion of the Regional Hospital of the Axarqu\u00eda<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-construccion-completes-the-expansion-of-the-regional-hospital-of-the-axarquia\" title=\"Sando Construcci\u00f3n completes the expansion of the Regional Hospital of the Axarqu\u00eda\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Entrega-Premios-e1774270357736.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"El 9\u00ba Open Nacional de P\u00e1del en Silla, Torneo Ciudad de Sevilla se ha celebrado en las instalaciones del Real Club Pineda de Sevilla. El evento, organizado por la Asociaci\u00f3n IN (Asociaci\u00f3n para el Fomento del Deporte Adaptado en Andaluc\u00eda) y el CD Sporting Guadalquivir, ha contado una vez m\u00e1s con la colaboraci\u00f3n de Fundaci\u00f3n Sando, que apoya esta iniciativa desde su primera edici\u00f3n, reforzando su compromiso con el deporte accesible y la inclusi\u00f3n.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">The Sando Foundation reinforces its commitment to adapted sport with the IX Chair Padel Open<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/the-sando-foundation-reinforces-its-commitment-to-adapted-sport-with-the-ix-chair-padel-open\" title=\"The Sando Foundation reinforces its commitment to adapted sport with the IX Chair Padel Open\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/clausura-excellence-9edicion-2-1536x1025-1-e1773233092263.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"El Instituto de Posgrado CEU Andaluc\u00eda ha invitado al presidente de honor de Sando, Jos\u00e9 Luis S\u00e1nchez Dom\u00ednguez, y al presidente ejecutivo, Luis S\u00e1nchez Manzano, a la clausura de la IX edici\u00f3n del Excellence Program. Un acto institucional en el que participaron 20 estudiantes de los distintos centros de CEU en la regi\u00f3n, seleccionados por su m\u00e9rito acad\u00e9mico.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando presents its business model to the students of the Excellence Program of the CEU Postgraduate Institute<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-presents-its-business-model-to-the-students-of-the-excellence-program-of-the-ceu-postgraduate-institute\" title=\"Sando presents its business model to the students of the Excellence Program of the CEU Postgraduate Institute\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Propuesta-Dia-de-la-Mujer-2026.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Con motivo del D\u00eda Internacional de la Mujer, Sando reafirma su compromiso con la igualdad de oportunidades y la construcci\u00f3n de entornos laborales diversos, inclusivos y equitativos. La compa\u00f1\u00eda contin\u00faa avanzando en la reducci\u00f3n de la brecha de g\u00e9nero e impulsando la presencia femenina en \u00e1reas tradicionalmente masculinizadas dentro del sector de la construcci\u00f3n y los servicios.\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Propuesta-Dia-de-la-Mujer-2026.jpg 940w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Propuesta-Dia-de-la-Mujer-2026-250x210.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Propuesta-Dia-de-la-Mujer-2026-700x587.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Propuesta-Dia-de-la-Mujer-2026-768x644.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Propuesta-Dia-de-la-Mujer-2026-120x101.jpg 120w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando consolidates its commitment to equality on International Women&#8217;s Day<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-consolidates-its-commitment-to-equality-on-international-womens-day\" title=\"Sando consolidates its commitment to equality on International Women&#8217;s Day\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Entrega-Premios-Concurso-Puentes.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando ha respaldado la fase local del III Concurso Nacional de Puentes Agust\u00edn de Betancourt, una iniciativa promovida por las escuelas de Ingenier\u00eda Civil de las universidades p\u00fablicas espa\u00f1olas y el Colegio de Ingenieros de Caminos, Canales y Puertos (CICCP).\" srcset=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Entrega-Premios-Concurso-Puentes.jpg 1908w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Entrega-Premios-Concurso-Puentes-250x97.jpg 250w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Entrega-Premios-Concurso-Puentes-700x272.jpg 700w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Entrega-Premios-Concurso-Puentes-768x298.jpg 768w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Entrega-Premios-Concurso-Puentes-1536x597.jpg 1536w, https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/Entrega-Premios-Concurso-Puentes-120x47.jpg 120w\" sizes=\"(max-width: 1908px) 100vw, 1908px\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando supports the III Agust\u00edn de Betancourt National Bridge Competition<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-supports-the-iii-agustin-de-betancourt-national-bridge-competition\" title=\"Sando supports the III Agust\u00edn de Betancourt National Bridge Competition\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/03\/LOGO-CENTENARIO_1-scaled-e1772625602755.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Fundaci\u00f3n Sando se suma a la celebraci\u00f3n del A\u00f1o Revello, un programa cultural impulsado por el Museo Revello de Toro con motivo del centenario del pintor F\u00e9lix Revello de Toro, que cumplir\u00e1 cien a\u00f1os el pr\u00f3ximo 10 de junio.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">The Sando Foundation celebrates the Year of Revello, which commemorates the centenary of the painter&#8217;s birth<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/the-sando-foundation-celebrates-the-year-of-revello-which-commemorates-the-centenary-of-the-painters-birth\" title=\"The Sando Foundation celebrates the Year of Revello, which commemorates the centenary of the painter&#8217;s birth\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/02\/WhatsApp-Image-2025-02-27-at-16.46.15-1-scaled-e1772020590363.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"Conacon Sando ha comenzado los trabajos correspondientes a la segunda fase del Plan de Mejora de Barrios de Alcal\u00e1 de Henares.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\"><a href=\"https:\/\/www.sando.com\/en\/conacon-sando\" title=\"Sustainable infrastructure maintenance and energy solutions\" target=\"_blank\">Conacon<\/a> Sando begins the second phase of the Neighborhood Improvement Plan of Alcal\u00e1 de Henares<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/conacon-sando-begins-the-second-phase-of-the-neighborhood-improvement-plan-of-alcala-de-henares\" title=\"Conacon Sando begins the second phase of the Neighborhood Improvement Plan of Alcal\u00e1 de Henares\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/02\/Render-HospitalMaterno-Infantil-e1771851900729.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"han sido adjudicatarias de las obras del nuevo Hospital Materno Infantil de Huelva, una infraestructura estrat\u00e9gica del Servicio Andaluz de Salud\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando Construcci\u00f3n and OHLA will execute the new Maternal and Children&#8217;s Hospital of Huelva<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-construccion-and-ohla-will-execute-the-new-maternal-and-childrens-hospital-of-huelva\" title=\"Sando Construcci\u00f3n and OHLA will execute the new Maternal and Children&#8217;s Hospital of Huelva\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/02\/20260203_142716-scaled-e1771249105795.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando Construcci\u00f3n ha puesto en marcha la nueva EDAR de Madridejos tras la finalizaci\u00f3n de las obras de ejecuci\u00f3n de esta infraestructura. Este proyecto de ACUAES supera los 10 millones de euros de presupuesto y contribuir\u00e1 a la mejora de la calidad de las aguas que llegan al Parque Nacional de Las Tablas de Daimiel.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando Construcci\u00f3n completes the Madridejos WWTP project for ACUAES<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-construccion-completes-the-madridejos-wwtp-project-for-acuaes\" title=\"Sando Construcci\u00f3n completes the Madridejos WWTP project for ACUAES\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/02\/TercerHospitaldeMalaga_EstudioLamela-1-e1770047287708.webp\" class=\"attachment-full size-full wp-post-image\" alt=\"Primera piedra del nuevo hospital de M\u00e1laga, denominado Hospital Virgen de la Esperanza.\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">OHLA, Sando Construcci\u00f3n and Vialterra begin work on the new hospital in Malaga Virgen de la Esperanza<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/ohla-sando-construccion-and-vialterra-begin-work-on-the-new-hospital-in-malaga-virgen-de-la-esperanza\" title=\"OHLA, Sando Construcci\u00f3n and Vialterra begin work on the new hospital in Malaga Virgen de la Esperanza\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/01\/Imagen-5-scaled-e1768496346475.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Conacon Sando realiza la reforma integral del Parque Taller de La Cuesta para el Cabildo de Tenerife\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Conacon Sando carries out the comprehensive refurbishment of the La Cuesta Workshop Park for the Cabildo de Tenerife<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/conacon-sando-carries-out-the-comprehensive-refurbishment-of-the-la-cuesta-workshop-park-for-the-cabildo-de-tenerife\" title=\"Conacon Sando carries out the comprehensive refurbishment of the La Cuesta Workshop Park for the Cabildo de Tenerife\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"__item\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"total m-cardPost u-br-l overflow-hidden --post-default\" data-max-width=\"500\">\n\t<div class=\"total __bxImg\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.sando.com\/contenido\/subidas\/2026\/01\/pexels-pixabay-60504-scaled-e1768482690328.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"Sando certifica su Sistema de Gesti\u00f3n de Seguridad de la Informaci\u00f3n con AENOR conforme a la ISO 27001\" \/>\t\t\t<\/div>\n\t<div class=\"total __bxCnt u-br-m u-verde-700 u-bg-gray-200\">\n\t\t\t\t<div class=\"__bxTxt total u-nmB-lastchild u-nmT-firstchild u-pB-s\">\n\t\t\t<p class=\"ht-body-l u-bold\">Sando certifies its Information Security Management System with AENOR in accordance with ISO 27001<\/p>\n\t\t<\/div>\n\t\t<div class=\"__bxItems total\">\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a href=\"https:\/\/www.sando.com\/en\/actualidad\/sando-certifies-its-information-security-management-system-with-aenor-in-accordance-with-iso-27001\" title=\"Sando certifies its Information Security Management System with AENOR in accordance with ISO 27001\" class=\"__bxLink u-br-l u-verde-500\"><\/a>\t\t\t\t\t\t\t\n<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"__footer total u-pT-s\">\r\n\t\t\t\t\t<div class=\"__bx d-flex gap-4\">\r\n\t\t\t\t\t\t<div class=\"__arrow-prev a-arrowSliderCircle\" role=\"button\" aria-label=\"Anterior\">\r\n\t\t\t\t\t\t\t<svg class=\"a-icon\"><use xlink:href=\"#icon-arrow-green-left-max\" href=\"\/i.svg#icon-arrow-green-left-max\"><\/use><\/svg>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"__arrow-next a-arrowSliderCircle\" role=\"button\" aria-label=\"Siguiente\">\r\n\t\t\t\t\t\t\t<svg class=\"a-icon\"><use xlink:href=\"#icon-arrow-green-right-max\" href=\"\/i.svg#icon-arrow-green-right-max\"><\/use><\/svg>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"__bx d-flex\">\r\n\t\t\t\t\t\t<div class=\"__counter\">\r\n\t\t\t\t\t\t\t<span class=\"ht-body-m u-bold __pageInfo\"><\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t<\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":26050,"parent":38394,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tax_brand":[1763,1765],"tax_services":[1499,1495,1498],"tax_location":[],"class_list":["post-38396","page","type-page","status-publish","has-post-thumbnail","hentry","tax_brand-conacon-en","tax_brand-sando-infraestructuras-y-proyectos-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roads, highways and motorways - Sando<\/title>\n<meta name=\"description\" content=\"We build and renovate highways, motorways and roads to adapt to the new needs that arise with the transformation of cities and towns.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roads, highways and motorways - Sando\" \/>\n<meta property=\"og:description\" content=\"We build and renovate highways, motorways and roads to adapt to the new needs that arise with the transformation of cities and towns.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads\" \/>\n<meta property=\"og:site_name\" content=\"Sando\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T18:32:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\\\/transport-and-mobility\\\/roads\",\"url\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\\\/transport-and-mobility\\\/roads\",\"name\":\"Roads, highways and motorways - Sando\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sando.com\\\/en#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\\\/transport-and-mobility\\\/roads#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\\\/transport-and-mobility\\\/roads#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sando.com\\\/contenido\\\/subidas\\\/2023\\\/12\\\/carreteras-autovia-polonia.jpg\",\"datePublished\":\"2023-11-01T18:17:11+00:00\",\"dateModified\":\"2026-06-03T18:32:43+00:00\",\"description\":\"We build and renovate highways, motorways and roads to adapt to the new needs that arise with the transformation of cities and towns.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\\\/transport-and-mobility\\\/roads#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\\\/transport-and-mobility\\\/roads\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\\\/transport-and-mobility\\\/roads#primaryimage\",\"url\":\"https:\\\/\\\/www.sando.com\\\/contenido\\\/subidas\\\/2023\\\/12\\\/carreteras-autovia-polonia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sando.com\\\/contenido\\\/subidas\\\/2023\\\/12\\\/carreteras-autovia-polonia.jpg\",\"width\":1900,\"height\":900,\"caption\":\"carreteras autovia polonia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\\\/transport-and-mobility\\\/roads#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.sando.com\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Specialisations\",\"item\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"transport infrastructure\",\"item\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Transportation and mobility\",\"item\":\"https:\\\/\\\/www.sando.com\\\/en\\\/specialisations\\\/transport-infrastructure\\\/transport-and-mobility\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"roads\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sando.com\\\/en#website\",\"url\":\"https:\\\/\\\/www.sando.com\\\/en\",\"name\":\"Sando\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sando.com\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sando.com\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sando.com\\\/en#organization\",\"name\":\"Sando\",\"url\":\"https:\\\/\\\/www.sando.com\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sando.com\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Sando\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sando.com\\\/en#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roads, highways and motorways - Sando","description":"We build and renovate highways, motorways and roads to adapt to the new needs that arise with the transformation of cities and towns.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads","og_locale":"en_US","og_type":"article","og_title":"Roads, highways and motorways - Sando","og_description":"We build and renovate highways, motorways and roads to adapt to the new needs that arise with the transformation of cities and towns.","og_url":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads","og_site_name":"Sando","article_modified_time":"2026-06-03T18:32:43+00:00","og_image":[{"width":1900,"height":900,"url":"https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads","url":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads","name":"Roads, highways and motorways - Sando","isPartOf":{"@id":"https:\/\/www.sando.com\/en#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads#primaryimage"},"image":{"@id":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads#primaryimage"},"thumbnailUrl":"https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia.jpg","datePublished":"2023-11-01T18:17:11+00:00","dateModified":"2026-06-03T18:32:43+00:00","description":"We build and renovate highways, motorways and roads to adapt to the new needs that arise with the transformation of cities and towns.","breadcrumb":{"@id":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads#primaryimage","url":"https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia.jpg","contentUrl":"https:\/\/www.sando.com\/contenido\/subidas\/2023\/12\/carreteras-autovia-polonia.jpg","width":1900,"height":900,"caption":"carreteras autovia polonia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility\/roads#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.sando.com\/en"},{"@type":"ListItem","position":2,"name":"Specialisations","item":"https:\/\/www.sando.com\/en\/specialisations"},{"@type":"ListItem","position":3,"name":"transport infrastructure","item":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure"},{"@type":"ListItem","position":4,"name":"Transportation and mobility","item":"https:\/\/www.sando.com\/en\/specialisations\/transport-infrastructure\/transport-and-mobility"},{"@type":"ListItem","position":5,"name":"roads"}]},{"@type":"WebSite","@id":"https:\/\/www.sando.com\/en#website","url":"https:\/\/www.sando.com\/en","name":"Sando","description":"","publisher":{"@id":"https:\/\/www.sando.com\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sando.com\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sando.com\/en#organization","name":"Sando","url":"https:\/\/www.sando.com\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sando.com\/en#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Sando"},"image":{"@id":"https:\/\/www.sando.com\/en#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/pages\/38396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/comments?post=38396"}],"version-history":[{"count":0,"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/pages\/38396\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/pages\/38394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/media\/26050"}],"wp:attachment":[{"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/media?parent=38396"}],"wp:term":[{"taxonomy":"tax_brand","embeddable":true,"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/tax_brand?post=38396"},{"taxonomy":"tax_services","embeddable":true,"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/tax_services?post=38396"},{"taxonomy":"tax_location","embeddable":true,"href":"https:\/\/www.sando.com\/en\/wp-json\/wp\/v2\/tax_location?post=38396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}